{"id":177,"count":22,"description":"","link":"https:\/\/finnmaster.fi\/sv\/equipment-type\/lisavarusteet-husky-r8-sv\/","name":"Lis\u00e4varusteet \/ Husky R8","slug":"lisavarusteet-husky-r8-sv","taxonomy":"equipment-type","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lis\u00e4varusteet \/ Husky R8-arkiv - Finnmaster-veneet<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/finnmaster.web.mediasignal.dev\/sv\/equipment-type\/lisavarusteet-husky-r8-sv\/\" \/>\n<meta property=\"og:locale\" content=\"sv_SE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lis\u00e4varusteet \/ Husky R8-arkiv - Finnmaster-veneet\" \/>\n<meta property=\"og:url\" content=\"https:\/\/finnmaster.web.mediasignal.dev\/sv\/equipment-type\/lisavarusteet-husky-r8-sv\/\" \/>\n<meta property=\"og:site_name\" content=\"Finnmaster-veneet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/finnmaster.web.mediasignal.dev\/sv\/equipment-type\/lisavarusteet-husky-r8-sv\/\",\"url\":\"https:\/\/finnmaster.web.mediasignal.dev\/sv\/equipment-type\/lisavarusteet-husky-r8-sv\/\",\"name\":\"Lis\u00e4varusteet \/ Husky R8-arkiv - Finnmaster-veneet\",\"isPartOf\":{\"@id\":\"https:\/\/finnmaster.fi\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/finnmaster.web.mediasignal.dev\/sv\/equipment-type\/lisavarusteet-husky-r8-sv\/#breadcrumb\"},\"inLanguage\":\"sv-SE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/finnmaster.web.mediasignal.dev\/sv\/equipment-type\/lisavarusteet-husky-r8-sv\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/finnmaster.fi\/sv\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lis\u00e4varusteet \/ Husky R8\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/finnmaster.fi\/#website\",\"url\":\"https:\/\/finnmaster.fi\/\",\"name\":\"Finnmaster-veneet\",\"description\":\"High-class Power Boats\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/finnmaster.fi\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sv-SE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lis\u00e4varusteet \/ Husky R8-arkiv - Finnmaster-veneet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/finnmaster.web.mediasignal.dev\/sv\/equipment-type\/lisavarusteet-husky-r8-sv\/","og_locale":"sv_SE","og_type":"article","og_title":"Lis\u00e4varusteet \/ Husky R8-arkiv - Finnmaster-veneet","og_url":"https:\/\/finnmaster.web.mediasignal.dev\/sv\/equipment-type\/lisavarusteet-husky-r8-sv\/","og_site_name":"Finnmaster-veneet","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/finnmaster.web.mediasignal.dev\/sv\/equipment-type\/lisavarusteet-husky-r8-sv\/","url":"https:\/\/finnmaster.web.mediasignal.dev\/sv\/equipment-type\/lisavarusteet-husky-r8-sv\/","name":"Lis\u00e4varusteet \/ Husky R8-arkiv - Finnmaster-veneet","isPartOf":{"@id":"https:\/\/finnmaster.fi\/#website"},"breadcrumb":{"@id":"https:\/\/finnmaster.web.mediasignal.dev\/sv\/equipment-type\/lisavarusteet-husky-r8-sv\/#breadcrumb"},"inLanguage":"sv-SE"},{"@type":"BreadcrumbList","@id":"https:\/\/finnmaster.web.mediasignal.dev\/sv\/equipment-type\/lisavarusteet-husky-r8-sv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/finnmaster.fi\/sv\/"},{"@type":"ListItem","position":2,"name":"Lis\u00e4varusteet \/ Husky R8"}]},{"@type":"WebSite","@id":"https:\/\/finnmaster.fi\/#website","url":"https:\/\/finnmaster.fi\/","name":"Finnmaster-veneet","description":"High-class Power Boats","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/finnmaster.fi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sv-SE"}]}},"_links":{"self":[{"href":"https:\/\/finnmaster.fi\/sv\/wp-json\/wp\/v2\/equipment-type\/177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finnmaster.fi\/sv\/wp-json\/wp\/v2\/equipment-type"}],"about":[{"href":"https:\/\/finnmaster.fi\/sv\/wp-json\/wp\/v2\/taxonomies\/equipment-type"}],"wp:post_type":[{"href":"https:\/\/finnmaster.fi\/sv\/wp-json\/wp\/v2\/equipment?equipment-type=177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}